{"id":160,"date":"2010-10-12T02:07:27","date_gmt":"2010-10-12T02:07:27","guid":{"rendered":"http:\/\/y-jesus.org\/spanish\/?page_id=160"},"modified":"2026-03-17T22:02:12","modified_gmt":"2026-03-17T22:02:12","slug":"1-era-jesus-una-persona-real","status":"publish","type":"page","link":"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/","title":{"rendered":"\u00bfEra Jes\u00fas una persona real?"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Nacido de identificaci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Identificaci\u00f3n de Nacimiento<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfExisti\u00f3 realmente Cristo Jes\u00fas, o fue el Cristianismo construido sobre un mito? Pocos estudiantes se cuestionan la existencia de Cristo, pero algunos enemigos del Cristianismo est\u00e1n intentando probar lo contrario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un pleito contra el Vaticano, la Iglesia fue acusada de inventar la historia de la existencia de Jes\u00fas. Aunque el caso fue visto fuera de la corte en febrero del 2006, el demandante, Luigi Cascioli, apel\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El argumento contra la existencia de Jes\u00fas fue hecho p\u00fablico en el programa del Se\u00f1or Larry King que era transmitido a nivel nacional por la cadena televisiva CNN con la siguiente declaraci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cBueno, yo estoy aqu\u00ed para dar el punto de vista real, supongo\u201d declar\u00f3 Ellen Johnson, presidente de Ateos Estadounidenses. <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cPorque la realidad es que, no hay una sola prueba de evidencia secular de que hubo un Jesucristo. Jesucristo y el Cristianismo es una religi\u00f3n moderna. Cristo Jes\u00fas es una recopilaci\u00f3n de otros dioses mitol\u00f3gicos, quienes tienen el mismo origen, y la misma muerte tal como la de Jesucristo.\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Johnson y un panel de l\u00edderes religiosos estuvieron discutiendo la pregunta, \u201c\u00bfQu\u00e9 pasa despu\u00e9s de que morimos? en una transmisi\u00f3n de&nbsp;<em>Larry King Live&nbsp;<\/em>en CNN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El usualmente flem\u00e1tico Larry King se detuvo reflexivamente y despu\u00e9s contesto:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201c\u00bfEntonces usted no cree que hubo un Cristo Jes\u00fas?\u201d Con un aire de certeza, Johnson respondi\u00f3: \u201cNo lo hubo. No hay evidencia secular de que Cristo Jes\u00fas existi\u00f3.\u201d <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">King no lo comprend\u00eda y fue a un corte comercial. Ninguna discusi\u00f3n acerca de la evidencia a favor o en contra de la existencia de Jes\u00fas vino despu\u00e9s. La audiencia de televisi\u00f3n nacional e internacional se qued\u00f3 con es pregunta sin resolver.<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">[1]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/2\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 2 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"tw-data-text vk_txt tw-ta tw-text-medium wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<p class=\"wp-block-paragraph\">Cincuenta a\u00f1os antes, en su libro <em>Why I Am Not a Christian<\/em> (Por qu\u00e9 yo no soy un Cristiano), el ateo Bertrand Russell dej\u00f3 en shock a su generaci\u00f3n al cuestionarse la existencia de Jes\u00fas. \u00c9l escribi\u00f3: \u201cHist\u00f3ricamente es bastante dudoso si Cristo alguna vez existi\u00f3 del todo, y si El existi\u00f3 nosotros no sabemos nada acerca El, entonces yo no estoy preocupado con la pregunta hist\u00f3rica, la cual es una bastante dif\u00edcil.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">[2]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es posible que el Jes\u00fas que muchos creen que es real nunca existi\u00f3? En The Story of Civilization (La Historia de la Civilizaci\u00f3n), el historiador secular Will Durant plante\u00f3 esta pregunta: \u201c\u00bfExisti\u00f3 Cristo? \u00bfEs la historia de vida del fundador del cristianismo el producto de la tristeza, la imaginaci\u00f3n, y la esperanza &#8211; un mito comparable a las leyendas de Krishna, Osiris, Attis, Adonis, Dioniso, y Mitras?\u201d<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[3]<\/a> Durant se\u00f1al\u00f3 c\u00f3mo la historia del cristianismo tiene \u00abmuchas semejanzas sospechosas a las leyendas de dioses paganos.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[4] <\/a>\u00bfEntonces, c\u00f3mo podemos nosotros saber por seguro que este hombre, a quienes muchos adoran y otros maldicen, fue real?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEsta Johnson en lo correcto cuando afirma que Cristo Jes\u00fas es una \u201crecopilaci\u00f3n de otros dioses\u201d? \u00bfY esta Russell en lo correcto cuando dice que la existencia de Jes\u00fas es \u201cbastante dudosa\u201d?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/3\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 3 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<h3 class=\"wp-block-heading\">Mito Vs. Realidad<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos a comenzar con una pregunta m\u00e1s fundamental: \u00bfQu\u00e9 distingue el mito de la realidad? \u00bfC\u00f3mo sabemos, por ejemplo, que Alejandro Magno existi\u00f3 realmente? Supuestamente, en el a\u00f1o 336 aC, Alejandro Magno se convirti\u00f3 en rey de Macedonia a los 20 a\u00f1os de edad. Un genio militar, \u00e9ste apuesto y arrogante l\u00edder masacro a trav\u00e9s de su camino aldeas, ciudades, y reinos del mundo Greco-Persa hasta que \u00e9l los gobern\u00f3 todos. En breves ocho a\u00f1os el ej\u00e9rcito de Alejandro hab\u00eda atravesado un total de 22,000 millas en sus conquistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ha dicho de Alejandro que el llor\u00f3 cuando se qued\u00f3 sin mundos por conquistar. (Estoy pensando, esta no es la persona con quien quiero jugar monopolio.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de que el muriera a la edad de 32 a\u00f1os, Alejandro seg\u00fan se informa, logr\u00f3 el m\u00e1s grande acto militar que ninguno otro la historia, no s\u00f3lo de los reyes que hab\u00edan vivido antes de \u00e9l, pero tambi\u00e9n de esos que estaban por venir m\u00e1s tarde, hasta a nuestro propio tiempo. Pero hoy, con excepci\u00f3n de un pu\u00f1ado de ciudades llamadas Alejandr\u00eda, una pel\u00edcula aburrida de Oliver Stone, y unos cuantos libros, su legado qued\u00f3 en el olvido. De hecho, el nombre de Colin Farrell tiene m\u00e1s poder de atracci\u00f3n en la taquilla que el de Alejandro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar del fracaso de taquilla, los historiadores creen que Alejandro existi\u00f3 debido a tres razones principales:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Documentaci\u00f3n escrita desde principios de los historiadores<\/li>\n\n\n\n<li>Impacto hist\u00f3rico<\/li>\n\n\n\n<li>Otras evidencias hist\u00f3ricas y arqueol\u00f3gicas<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Documentos Hist\u00f3ricos Sobre Jes\u00fas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lo hist\u00f3rico de Alejandro Magno y sus conquistas militares se extrae de cinco fuentes antiguas, ninguna de las cuales fueron escritas por testigos presenciales. Aunque escrito 400 a\u00f1os despu\u00e9s de Alejandro, La Vida de Alejandro de Plutarco es el primer relato de su vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Plutarco y los otros escritores hubo varios cientos de a\u00f1os alejados de los acontecimientos de la vida de Alejandro, ellos basan su informaci\u00f3n en relatos anteriores. De los veinte relatos hist\u00f3ricos contempor\u00e1neos de Alejandro, ninguno sobrevive. M\u00e1s tarde existieron relatos, pero cada uno presenta un \u201cAlejandro\u201d diferente, lo que deja mucho a nuestra imaginaci\u00f3n. Pero a pesar de la diferencia de tiempo de varios cientos de a\u00f1os, los historiadores est\u00e1n convencidos de que Alejandro fue un hombre real y que los detalles esenciales de lo que nosotros leemos acerca de su vida son verdades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dejando a Alejandro como un punto de referencia, nosotros notaremos que para Jes\u00fas hay ambos relatos hist\u00f3ricos religiosos y seculares. Pero debemos hacer la pregunta, \u00bffueron escritos por historiadores fiables y objetivos? Echemos una breve mirada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/4\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 4 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<h3 class=\"wp-block-heading\">El Nuevo Testamento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los 27 libros del Nuevo Testamento afirman ser escritos por autores quienes conoc\u00edan a Jes\u00fas o recibieron el conocimiento de El de primera mano por parte de otros. Los cuatro evangelios relatan informaci\u00f3n de la vida de Jes\u00fas y sus palabras desde diferentes perspectivas. Estos relatos han sido fuertemente estudiados por eruditos tanto dentro como fuera del Cristianismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acad\u00e9mico John Dominic Crossan cree que menos del 20 porciento de lo que leemos en los evangelios son frases originales de Jes\u00fas. Sin embargo, a\u00fan este esc\u00e9ptico no discute que Cristo Jes\u00fas realmente vivi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de las opiniones de Crossan, y las de algunos otros estudiosos marginales como \u00e9l, el consenso de la mayor\u00eda de historiadores es que los relatos del Evangelio nos dan una imagen clara de Cristo Jes\u00fas. Si los relatos del Nuevo Testamento son dignos de confianza es el tema de otro articulo (ver \u201c<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj\/3-ed-jesus-dio\/\" target=\"_blank\" rel=\"noopener noreferrer\">Jesus.doc\u201d<\/a>), entonces nosotros veremos fuentes no-Cristianas para nuestra respuesta de si Jes\u00fas existi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/5\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 5 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<h3 class=\"wp-block-heading\">Los Primeros Relatos No-Cristianos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed que, \u00bfcu\u00e1les historiadores del primer siglo no ten\u00edan una agenda Cristiana? Primero que todo, vamos a ver a los enemigos de Jes\u00fas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus oponentes jud\u00edos ten\u00edan m\u00e1s que ganar negando la existencia de Jes\u00fas. Pero la evidencia apuntaba en la direcci\u00f3n opuesta. Varios escritos jud\u00edos tambi\u00e9n dicen de la existencia de su carne y sangre. Ambas Guemar\u00e1s del Talmud jud\u00edo se refieren a Jes\u00fas. A pesar de que estos consisten en s\u00f3lo unos pocos y breves, amargos pasajes con la intenci\u00f3n de descontar la deidad de Jes\u00fas, estos primeros escritos jud\u00edos no comienzan a insinuar que El no fuera una persona hist\u00f3rica.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[5]<\/a><sup><br><\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Flavio Josefo fue un destacado historiador jud\u00edo quien empez\u00f3 a escribir bajo la autoridad romana en 67 A.D. Josefo, quien naci\u00f3 solo unos pocos a\u00f1os despu\u00e9s de que Jes\u00fas muri\u00f3, habr\u00eda sido muy consciente de la reputaci\u00f3n de Jes\u00fas entre ambos romanos y jud\u00edos. En su famoso <em>Antiquities of the Jews<\/em> (Antig\u00fcedades de los Jud\u00edos) en el 93 A.D., Josefo escribi\u00f3 sobre Jes\u00fas como una persona real. \u201cEn ese momento vivi\u00f3 Jes\u00fas, un hombre santo, si \u00e9l puede ser llamado hombre, porque \u00e9l realizo obras maravillosas, y ense\u00f1o a hombres, y recibi\u00f3 con alegr\u00eda la verdad. Y \u00e9l fue seguido por muchos jud\u00edos y muchos griegos. \u00c9l era el Mes\u00edas.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[6]<\/a>Aunque hay disputa sobre algunas de las redacciones de los relatos, especialmente la referencia de Jes\u00fas siendo el Mes\u00edas (los estudiosos son esc\u00e9pticos, pensando que los Cristianos insertaron esta frase), claramente Josefo confirm\u00f3 esta existencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 hay de los historiadores seculares, aquellos que vivieron en tiempos antiguos pero que no eran religiosamente motivados? Hay confirmaci\u00f3n actual de al menos 19 escritores seculares tempranos quienes hicieron referencias de Jes\u00fas como una persona real.<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[7]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los m\u00e1s grandes historiadores antiguos, Cornelio T\u00e1cito, afirm\u00f3 que Jes\u00fas hab\u00eda sufrido bajo Pilatos. T\u00e1cito naci\u00f3 alrededor de 25 a\u00f1os despu\u00e9s de la muerte de Jes\u00fas, y el hab\u00eda visto como la propagaci\u00f3n del Cristianismo empez\u00f3 a impactar a Roma. El historiador romano escribi\u00f3 negativamente de Cristo y los cristianos, identific\u00e1ndolos en a\u00f1o 115 A.D. como \u201cuna raza de hombres detestados por sus malas pr\u00e1cticas, y com\u00fanmente llamadas Chrestiani. El nombre fue derivado de Chrestus, quien, en la regi\u00f3n de Tiberio, sufri\u00f3 bajo Poncio Pilatos, procurador de Judea.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[8]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/6\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 6 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<h3 class=\"wp-block-heading\">Los siguientes hechos sobre Jes\u00fas fueron escritos por fuentes tempranas no cristianas:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jes\u00fas era de Nazaret<\/li>\n\n\n\n<li>Jes\u00fas vivi\u00f3 una sabia y virtuosa vida<\/li>\n\n\n\n<li>Jes\u00fas fue crucificado en Palestina bajo Poncio Pilatos durante el reinado de Tiberio C\u00e9sar en tiempo de Pascua, al ser considerado el rey jud\u00edo.<\/li>\n\n\n\n<li>Los disc\u00edpulos creyeron que Jes\u00fas que hab\u00eda muerto y resucitado de la muerte tres d\u00edas despu\u00e9s.<\/li>\n\n\n\n<li>Los enemigos de Jes\u00fas reconocieron que \u00e9l realizo haza\u00f1as inusuales que llamaron \u201cbrujer\u00eda\u201d<\/li>\n\n\n\n<li>La peque\u00f1a banda de disc\u00edpulos de Jes\u00fas se multiplic\u00f3 r\u00e1pidamente, expandi\u00e9ndose tanto como Roma.<\/li>\n\n\n\n<li>Los disc\u00edpulos de Jes\u00fas negaron el polite\u00edsmo, vivieron vidas morales, y adoraron a Cristo como Dios<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El te\u00f3logo Norman Geisler coment\u00f3:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Este esquema general es perfectamente congruente con el del Nuevo Testamento.<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">&nbsp;[9]<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Todos estos relatos independientes, religiosos y seculares, hablan sobre un hombre real que coincide bien con el Jes\u00fas de los evangelios. La enciclopedia Brit\u00e1nica cita estos diversos relatos seculares de la vida de Jes\u00fas como prueba convincente de su existencia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Estos relatos independientes prueban que en tiempos antiguos incluso los oponentes del Cristianismo no dudaron de la historicidad de Jes\u00fas.<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[10]<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/7\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 7 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Impacto Hist\u00f3rico<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una importante distinci\u00f3n entre un mito y una persona real es como la figura impacta la historia. Por ejemplo, los Juegos Ol\u00edmpicos se originaron en el Monte Ol\u00edmpico en Grecia, casa del templo Griego al dios Zeus. Pero Zeus no ha cambiado los gobiernos, las leyes o la \u00e9tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El historiador Thomas Carlyle dijo: \u201cNing\u00fan gran hombre vive en vano. La historia del mundo no es sino la biograf\u00eda de grandes hombres.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[11]<\/a> Como Carlyle observa, es la gente real, no los mitos, quienes impactan la historia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como una persona real, Alejandro impacto la historia por sus conquistas militares, alterando las naciones, los gobiernos y las leyes. \u00bfPero que de Cristo Jes\u00fas y su impacto en nuestro mundo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los gobiernos del primer siglo de Israel y Roma fueron en gran parte poco afectados por la vida de Jes\u00fas. El promedio de ciudadanos romanos no supieron que \u00e9l existi\u00f3 hasta muchos a\u00f1os despu\u00e9s de su muerte, la cultura romana permaneci\u00f3 en gran parte distante de sus ense\u00f1anzas por d\u00e9cadas, y pasar\u00edan varios a\u00f1os antes de que matar cristianos en el coliseo se convirtiera en un pasatiempo nacional. El resto del mundo ten\u00eda poco si acaso ning\u00fan conocimiento de \u00e9l. Jes\u00fas no fue oficial de un ej\u00e9rcito. El no escribi\u00f3 un libro o cambi\u00f3 alguna ley. Los l\u00edderes jud\u00edos esperaban borrarlo de sus memorias, y parec\u00eda que tendr\u00edan \u00e9xito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, sin embargo, la antigua Roma se encuentra en ruinas. Las poderosas legiones del Cesar y la pompa del poder del imperio romano se han desvanecido en el olvido. Sin embargo, \u00bfc\u00f3mo es Jes\u00fas recordado hoy? \u00bfCu\u00e1l es su influencia duradera?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00e1s libros han sido escritos sobre Jes\u00fas que sobre alguna otra persona en la historia.<\/li>\n\n\n\n<li>Naciones han usado sus palabras como la piedra angular de sus gobiernos. De acuerdo con Durant: \u201cEl triunfo de Cristo fue el comienzo de la democracia.\u201d<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[12]<\/a><\/li>\n\n\n\n<li>Su serm\u00f3n del Monte estableci\u00f3 un nuevo paradigma en la \u00e9tica y la moral.<\/li>\n\n\n\n<li>Las escuelas, hospitales y obras humanitarias se han fundado en su nombre. Harvard, Yale, Princeton y Oxford son sino unas pocas universidades que tienen cristianos para dar gracias por sus comienzos.<\/li>\n\n\n\n<li>El elevado papel de la mujer en la cultura occidental traza sus ra\u00edces de vuelta a Jes\u00fas.(Las mujeres en los d\u00edas de Jes\u00fas eran consideradas inferiores y virtualmente \u201cno personas\u201d hasta que su ense\u00f1anza fue seguida)<\/li>\n\n\n\n<li>La esclavitud fue abolida en Gran Breta\u00f1a y los Estados Unidos debido a las ense\u00f1anzas de Jes\u00fas que cada vida humana es valiosa.<\/li>\n\n\n\n<li>Exdrogadictos y dependientes al alcohol, prostitutas y otros en busca de prop\u00f3sito en la vida alegan que \u00e9l es la explicaci\u00f3n de sus vidas cambiadas.<\/li>\n\n\n\n<li>Dos billones de personas se llaman a si mismos cristianos. Mientras algunos son cristianos de nombre solamente, otros siguen impactando nuestra cultura ense\u00f1ando los principios de Jes\u00fas, que toda vida es valiosa y que estamos para amarnos unos a otros.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/8\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 8 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<p class=\"wp-block-paragraph\">Extraordinariamente, Jes\u00fas hizo todos estos impactos como resultado de solo un per\u00edodo de tres a\u00f1os de ministerio p\u00fablico. Si Jes\u00fas no existi\u00f3, uno debe preguntarse como un mito podr\u00eda alterar la historia. Cuando al historiador mundial H.G. Wells se le pregunto qui\u00e9n ha dejado el mayor legado en la historia, \u00e9l respondi\u00f3: \u201cEn esta prueba Jes\u00fas se mantiene primero.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[13]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La evidencia documental y el impacto hist\u00f3rico se\u00f1alan el hecho de que Jes\u00fas si existi\u00f3. Si Jes\u00fas realmente existi\u00f3, nosotros tambi\u00e9n esperar\u00edamos descubrir sus huellas impresas dentro de los detalles de la historia. Los mitos no dejan tal confirmaci\u00f3n de detalles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las claves aqu\u00ed para Durant y otros estudiosos es el factor tiempo. Los mitos y leyendas usualmente toman cientos de a\u00f1os para evolucionar- la historia de que George Washington nunca dijo una mentira es probablemente una mentira, hasta dos siglos despu\u00e9s se convirti\u00f3 en una leyenda. Las Buenas Nuevas del cristianismo, por otro lado, despegaron tan r\u00e1pido como para ser un mito o una leyenda. Jes\u00fas no hab\u00eda existido, aquellos que se opusieron el cristianismo sin duda le han marcado un mito desde el principio. Pero ellos no lo hicieron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tales evidencias, junto con los relatos escritos desde principios y el impacto hist\u00f3rico de Cristo Jes\u00fas, convence incluso a los historiadores esc\u00e9pticos de que el fundador del cristianismo no fue ni un mito ni una leyenda. Pero un experto en mitos no estaba tan seguro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como Muggeridge, estudioso de Oxford, C.S. Lewis estaba inicialmente convencido de que Jes\u00fas no era nada sino un mito. Lewis dijo una vez: \u201cTodas las religiones, eso es, toda mitolog\u00eda\u2026 son meramente invenci\u00f3n propia del hombre- Cristo tanto como Loki.:<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[14] <\/a>(Loki es un antiguo dios n\u00f3rdico. Al igual que Thor pero sin una cola en el pelo.)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diez a\u00f1os despu\u00e9s de denunciar a Jes\u00fas como mito, Lewis descubri\u00f3 los detalles hist\u00f3ricos, incluyendo varios documentos de testigos, verificando su existencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jesucristo ha impactado el paisaje hist\u00f3rico como un terremoto masivo. Y este terremoto ha dejado un sendero m\u00e1s ancho que el Gran Ca\u00f1\u00f3n. Es este sendero de evidencia que convence a estudiosos que Jes\u00fas realmente existi\u00f3 y realmente impact\u00f3 nuestro mundo hace 2000 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/9\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 9 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<p class=\"wp-block-paragraph\">Un esc\u00e9ptico quien pens\u00f3 que Jes\u00fas era un mito fue el periodista brit\u00e1nico Malcolm Muggeridge. Pero en un trabajo en televisi\u00f3n a Israel, Muggeridge fue enfrentado con evidencia sobre Jesucristo que \u00e9l no sab\u00eda que exist\u00eda. As\u00ed como \u00e9l revis\u00f3 lugares hist\u00f3ricos &#8211; el lugar de nacimiento de Jes\u00fas, Nazaret, el lugar de la crucifixi\u00f3n y la tumba vac\u00eda- un sentido de la realidad de Jes\u00fas empez\u00f3 a emerger.<br>M\u00e1s tarde el declar\u00f3:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Fue mientras yo estaba en Tierra Santa con el prop\u00f3sito de hacer tres BBC programas de televisi\u00f3n en el Nuevo Testamento que\u2026 ciertamente el nacimiento de Jes\u00fas me tom\u00f3, ministerio y crucifixi\u00f3n\u2026 me volv\u00ed consciente de que realmente hab\u00eda habido un hombre, Jes\u00fas, quien fue tambi\u00e9n Dios.<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[15]<\/a><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Un gran cr\u00edtico acad\u00e9mico alem\u00e1n, en los siglos 18 y 19, hab\u00eda cuestionado la existencia de Jes\u00fas, se\u00f1alando que tales figuras claves como Poncio Pilatos y el principal sacerdote Caif\u00e1s en los relatos de los evangelios nunca han sido confirmados como reales. No fue posible refutarle hasta mediados del siglo 20.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los arque\u00f3logos en 1962 confirmaron la existencia de Pilatos cuando ellos descubrieron su nombre incluido en una inscripci\u00f3n en una piedra excavada. Igualmente, la existencia de Caif\u00e1s fue un incierto hasta 1990, cuando un osario (hueso cuadrado) fue descubierto llevando su inscripci\u00f3n. Los arque\u00f3logos han descubierto tambi\u00e9n lo que ellos creen es la casa de Sim\u00f3n Pedro y la cueva donde Juan el Bautista hizo su bautismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, tal vez la evidencia m\u00e1s convincente de que Jes\u00fas existi\u00f3 fue el r\u00e1pido levantamiento de los cristianos. \u00bfC\u00f3mo puede explicarse sin Jes\u00fas? \u00bfC\u00f3mo puede este grupo de pescadores y otros hombres trabajadores inventar a Jes\u00fas en unos escasos a\u00f1os? Durant respondi\u00f3 su pregunta introductoria -\u00bfExiste Cristo?- con la siguiente conclusi\u00f3n:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Que unos pocos y simples hombres debieran en una generaci\u00f3n haber inventado tan poderosa y atractiva personalidad, tan elevada \u00e9tica y tan inspirada visi\u00f3n de la fraternidad humana, ser\u00eda un milagro mucho m\u00e1s incre\u00edble que ning\u00fan otro relatado en los evangelios. Despu\u00e9s de dos siglos de mayor critica las l\u00edneas generales de la vida, el car\u00e1cter y la ense\u00f1anza de Cristo, permanece razonablemente limpio, y constituye el m\u00e1s fascinante rasgo en la historia del hombre occidental.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/y-jesus.org\/spanish\/wwrj\/1-era-jesus-una-persona-real\/10\/\">Haga clic aqu\u00ed para continuar leyendo la p\u00e1gina 10 de 10 de \u00bfEra Jes\u00fas una persona real?<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n\n<!--nextpage-->\n\n\n\n<h3 class=\"wp-block-heading\">Veredicto De Eruditos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Clifford Herschel Moore, professor de la Universidad de Harvard, afirm\u00f3 en cuanto a la historicidad de Jes\u00fas: \u201cEl cristianismo conoci\u00f3 a su Salvador y Redentor no como cualquier dios en cuya historia estaba contenida alguna f\u00e9 m\u00edtica\u2026 Jes\u00fas fue hist\u00f3rico y no un ser m\u00edtico. Ning\u00fan mito remoto o falso ingres\u00f3 en el creyente Christiano; su fe fue fundada en hechos positivos, hist\u00f3ricos y aceptables.\u00bb<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[16]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pocos, si acaso algunos historiadores est\u00e1n de acuerdo con las afirmaciones de Ellen Johnson y Bertrand Russel que Jes\u00fas no existi\u00f3. La documentaci\u00f3n extensa de la vida de Jes\u00fas por autores contempor\u00e1neos, su profundo impacto hist\u00f3rico, y la evidencia a su favor tangible en la historia han persuadido a los eruditos acerca de que Jes\u00fas verdaderamente existi\u00f3. \u00bfPodr\u00eda un mito haber hecho todo eso? Todos excepto unos pocos dicen que no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Michael Grant de Cambridge ha escrito, \u201cPara resumir, los m\u00e9todos cr\u00edticos modernos no soportan la teor\u00eda del Cristo-mito. Una y otra vez ha sido contestado y descartado por eruditos de primera. En a\u00f1os recientes no hay ningun erudito serio que se atrever\u00eda a postular la no historicidad de Jes\u00fas.\u201d<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[17]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El historiador Jaroslav Pelikan declar\u00f3, \u201cSin importar lo que uno puede pensar o creer personalmente acerca de \u00e9l, Jes\u00fas de Nazaret ha sido la figura m\u00e1s dominante de la cultura occidental por veinte siglos\u2026 Es de su nacimiento que la mayor\u00eda de la raza humana fecha sus calendarios, es por su nombre que muchos maldicen y en su nombre que millones oran.\u201d<a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\" target=\"_blank\" rel=\"noopener noreferrer\">[18]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj\/6-se-levanto-jesus-de-entre-los-muertos\/\">Haga clic aqu\u00ed para echar un vistazo a las pruebas de la afirmaci\u00f3n m\u00e1s fant\u00e1stica jam\u00e1s se ha hecho &#8212; la resurrecci\u00f3n de Jesucristo!<\/a><\/p>\n\n\n\n<div style=\"text-align:center;\">\n  <a href=\"\/spanish\/enviar-comentario\/\"\n     style=\"display:inline-block;padding:14px 26px;background:#1e73be;color:#fff;text-decoration:none;font-size:18px;font-weight:700;line-height:1.3;border-radius:8px;border:2px solid #1e73be;text-align:center;\">\n    Por favor, deje un comentario\n  <\/a>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/y-jesus.org\/spanish\/wwrj-endnotes\/endnotes-1-era-jesus-una-persona-rea\/\">notas finales<\/a><\/p>\n\n\n<hr \/>\r\n<!-- Event snippet for Sign up conversion page \/TTN -->\r\n<script>\r\n  gtag('event', 'conversion', {'send_to': 'AW-626542450\/bdj4CM-l5NQBEPKO4aoC'});\r\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Nacido de identificaci\u00f3n Identificaci\u00f3n de Nacimiento \u00bfExisti\u00f3 realmente Cristo Jes\u00fas, o fue el Cristianismo construido sobre un mito? Pocos estudiantes se cuestionan la existencia de Cristo, pero algunos enemigos del Cristianismo est\u00e1n intentando probar lo contrario. En un pleito contra el Vaticano, la Iglesia fue acusada de inventar la historia de la existencia de Jes\u00fas. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":162,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":["post-160","page","type-page","status-publish","entry"],"featured_image_src":null,"featured_image_src_square":null,"coauthors":[],"author_meta":{"author_link":"https:\/\/y-jesus.org\/spanish\/author\/admin\/","display_name":"admin"},"relative_dates":{"created":"Publicado 16 a\u00f1os hace","modified":"Actualizado 6 meses hace"},"absolute_dates":{"created":"Publicado el octubre 12, 2010","modified":"Actualizado el marzo 17, 2026"},"absolute_dates_time":{"created":"Publicado el octubre 12, 2010 2:07 am","modified":"Actualizado el marzo 17, 2026 10:02 pm"},"featured_img_caption":"","featured_img":false,"series_order":"","_links":{"self":[{"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/pages\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":4,"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/pages\/160\/revisions"}],"predecessor-version":[{"id":2076,"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/pages\/160\/revisions\/2076"}],"up":[{"embeddable":true,"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/pages\/162"}],"wp:attachment":[{"href":"https:\/\/y-jesus.org\/spanish\/wp-json\/wp\/v2\/media?parent=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}